{"id":2407,"date":"2020-03-13T16:06:32","date_gmt":"2020-03-13T19:06:32","guid":{"rendered":"http:\/\/www.exotics.com.br\/blog\/?p=1492"},"modified":"2020-03-13T16:06:32","modified_gmt":"2020-03-13T19:06:32","slug":"30-de-desconto-de-16-a-20-de-marco","status":"publish","type":"post","link":"https:\/\/www.exotics.com.br\/blog\/30-de-desconto-de-16-a-20-de-marco\/","title":{"rendered":"30% de desconto de 16 a 20 de mar\u00e7o"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.exotics.com.br\/blog\/wp-content\/uploads\/2020\/03\/dia-do-consumidor-5-1024x1024.png\" alt=\"\" class=\"wp-image-1493\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 claro que n\u00e3o ficar\u00edamos de fora do&nbsp;<strong>Dia do Consumidor<\/strong>!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De 16 a 20 de mar\u00e7o, adquira um\u00a0<strong>novo sistema<\/strong>\u00a0da Exotics Inform\u00e1tica ou fa\u00e7a o\u00a0<strong>upgrade de vers\u00e3o<\/strong>\u00a0com 30% de desconto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fale conosco e aproveite:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>(51) &nbsp;3028-4520<\/strong>,&nbsp;<strong>(51) 99976-1133<\/strong>&nbsp;e&nbsp;<a href=\"mailto:info@exotics.com.br\" target=\"_blank\" rel=\"noreferrer noopener\">info@exotics.com.br<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atendimento de segunda a sexta-feira, das 9h \u00e0s 17h30min.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>* A promo\u00e7\u00e3o n\u00e3o \u00e9 v\u00e1lida para Memorial \u00cdndices, Advoc Tribunais e renova\u00e7\u00e3o dos sistemas online.\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9 claro que n\u00e3o ficar\u00edamos de fora do&nbsp;Dia do Consumidor! De 16 a 20 de mar\u00e7o, adquira um\u00a0novo sistema\u00a0da Exotics Inform\u00e1tica ou fa\u00e7a o\u00a0upgrade de vers\u00e3o\u00a0com 30% de desconto. Fale conosco e aproveite: (51) &nbsp;3028-4520,&nbsp;(51) 99976-1133&nbsp;e&nbsp;info@exotics.com.br. Atendimento de segunda a sexta-feira, das 9h \u00e0s 17h30min. * A promo\u00e7\u00e3o n\u00e3o \u00e9 v\u00e1lida para Memorial \u00cdndices, Advoc [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,13],"tags":[],"class_list":["post-2407","post","type-post","status-publish","format-standard","hentry","category-empresa","category-sistemas"],"_links":{"self":[{"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/posts\/2407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2407"}],"version-history":[{"count":0,"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/posts\/2407\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}