{"id":829,"date":"2015-01-14T17:07:23","date_gmt":"2015-01-14T20:07:23","guid":{"rendered":"http:\/\/www.exotics.com.br\/blog\/?p=829"},"modified":"2015-01-14T17:07:23","modified_gmt":"2015-01-14T20:07:23","slug":"8-coisas-que-voce-precisa-entender-sobre-pessoas-para-liderar-equipes","status":"publish","type":"post","link":"https:\/\/www.exotics.com.br\/blog\/8-coisas-que-voce-precisa-entender-sobre-pessoas-para-liderar-equipes\/","title":{"rendered":"8 coisas que voc\u00ea precisa entender sobre pessoas para liderar equipes"},"content":{"rendered":"<p><a href=\"https:\/\/www.exotics.com.br\/blog\/wp-content\/uploads\/2015\/02\/pessoas.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-830\" src=\"https:\/\/www.exotics.com.br\/blog\/wp-content\/uploads\/2015\/02\/pessoas.png\" alt=\"pessoas\" width=\"500\" height=\"500\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Voc\u00ea \u00e9 um gerente financeiro de uma companhia? \u00c9 o vice-presidente de opera\u00e7\u00f5es? Ou quem sabe o diretor de desenvolvimento? N\u00e3o importa. No fundo, voc\u00ea \u00e9 um gestor de pessoas. Independente da ind\u00fastria, da empresa, ou mesmo do t\u00edtulo do cargo, todos os gerentes s\u00e3o gestores de pessoas, toda gest\u00e3o \u00e9 uma gest\u00e3o de gente.<\/p>\n<p style=\"text-align: justify;\">Para o especialista em carreiras Pablo Aversa, o profissional que \u00e9 respons\u00e1vel pelos resultados de um grupo de pessoas precisa saber algumas coisas importantes sobre gente:<\/p>\n<h4 style=\"text-align: justify;\">Pessoas s\u00e3o indiv\u00edduos<\/h4>\n<p style=\"text-align: justify;\">Independentemente das generaliza\u00e7\u00f5es que vir\u00e3o a seguir, \u00e9 importante lembrar-se de que n\u00e3o existem duas pessoas iguais. Elas t\u00eam sonhos individuais e preocupa\u00e7\u00f5es individuais. Suas mentes funcionam de forma diferente. Ouvem e enxergam de forma diferente. E, principalmente, s\u00e3o motivadas por coisas diferentes.<\/p>\n<h4 style=\"text-align: justify;\">Pessoas s\u00e3o imprevis\u00edveis<\/h4>\n<p style=\"text-align: justify;\">Ficam com raiva. Ficam preocupadas. Algumas vezes choram, ou gritam, ou se isolam (e ainda fazem beicinho). N\u00e3o importa o quanto j\u00e1 tenha trabalhado com gente, voc\u00ea nunca vai estar completamente seguro de como v\u00e3o reagir.<\/p>\n<h4 style=\"text-align: justify;\">Pessoas s\u00e3o ego\u00edstas<\/h4>\n<p style=\"text-align: justify;\">Pessoas cuidam de si mesmas. Sabem que ningu\u00e9m, nem mesmo o esposo ou a esposa, est\u00e1 t\u00e3o preocupado com seu bem-estar quanto elas mesmas. Podem at\u00e9 n\u00e3o saber qual \u00e9 a melhor forma de conquist\u00e1-lo, mas sabem muito bem o que consideram ser o melhor para elas e correm com afinco atr\u00e1s disso. Algumas s\u00e3o melhores que outras nesse aspecto, mas pode ter certeza: todas desejam esse bem-estar.<\/p>\n<h4 style=\"text-align: justify;\">Pessoas s\u00e3o generosas<\/h4>\n<p style=\"text-align: justify;\">Se as pessoas s\u00e3o ego\u00edstas, como ent\u00e3o tamb\u00e9m podem ser generosas? Veja, s\u00e3o generosas porque, mesmo quando cuidam de si, trabalham de forma colaborativa para ajudar os demais a chegar l\u00e1. Elas v\u00e3o correr atr\u00e1s primeiro daquilo que consideram sua fatia justa, mas, t\u00e3o logo conquistem seu quinh\u00e3o, v\u00e3o cuidar dos demais.<\/p>\n<h4 style=\"text-align: justify;\">Pessoas s\u00e3o vol\u00faveis<\/h4>\n<p style=\"text-align: justify;\">O que funcionou na semana passada, ou mesmo ontem, pode n\u00e3o funcionar hoje. A recompensa ou o desafio que motivou algu\u00e9m anteriormente pode n\u00e3o mais funcionar, simplesmente porque algo mudou no universo dela.<\/p>\n<h4 style=\"text-align: justify;\">Pessoas s\u00e3o medrosas<\/h4>\n<p style=\"text-align: justify;\">Algumas pessoas s\u00e3o mais medrosas que outras. Outras escondem isso melhor. Mas todo mundo tem medo de algo. Seja o medo de perder o emprego, de parecer tolo na frente dos demais ou de n\u00e3o alcan\u00e7ar a meta pela primeira vez em dez anos, n\u00e3o importa: todos n\u00f3s temos medos. E at\u00e9 que voc\u00ea lide com os medos delas, as pessoas v\u00e3o continuar a se focar naquilo que as preocupam, em vez daquilo que voc\u00ea quer que elas fa\u00e7am.<\/p>\n<h4 style=\"text-align: justify;\">As pessoas s\u00e3o um barato<\/h4>\n<p style=\"text-align: justify;\">A somat\u00f3ria das individualidades acima \u00e9 o que acaba fazendo com que as pessoas sejam interessantes. E mais: isso \u00e9 o que faz com que elas sejam um barato. Como gestor de gente, voc\u00ea nunca ter\u00e1 um dia chato. Alguns dias ser\u00e3o melhores que outros. Alguns dias v\u00e3o fazer voc\u00ea querer gritar e espernear. Mas, com certeza, nenhum dos seus dias vai ser chato. Agora, se voc\u00ea n\u00e3o curte gente, n\u00e3o se envolva com gest\u00e3o, pois isso vai acabar sugando todo o prazer que, de alguma outra maneira, o seu dia poderia lhe proporcionar.<\/p>\n<h4 style=\"text-align: justify;\">Gente quer ser liderada<\/h4>\n<p style=\"text-align: justify;\">Como gestor de gente, voc\u00ea deve ir al\u00e9m e ser l\u00edder de gente. Se voc\u00ea n\u00e3o liderar as pessoas, algu\u00e9m vai. Pode ser outro funcion\u00e1rio do departamento (afinal, lideran\u00e7a \u00e9 uma habilidade, n\u00e3o um atributo que vem com o cargo) ou pode ser um gerente de outra \u00e1rea. O ponto \u00e9 que, com certeza, elas v\u00e3o seguir algu\u00e9m e algu\u00e9m ser\u00e1 o l\u00edder delas.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.administradores.com.br\/noticias\/carreira\/8-coisas-que-voce-precisa-entender-sobre-pessoas-para-liderar-equipes\/59000\/\" target=\"_blank\">Fonte: Portal Administradores<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea \u00e9 um gerente financeiro de uma companhia? \u00c9 o vice-presidente de opera\u00e7\u00f5es? Ou quem sabe o diretor de desenvolvimento? N\u00e3o importa. No fundo, voc\u00ea \u00e9 um gestor de pessoas. Independente da ind\u00fastria, da empresa, ou mesmo do t\u00edtulo do cargo, todos os gerentes s\u00e3o gestores de pessoas, toda gest\u00e3o \u00e9 uma gest\u00e3o de gente. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-829","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/posts\/829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/comments?post=829"}],"version-history":[{"count":0,"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/posts\/829\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/media?parent=829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/categories?post=829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.exotics.com.br\/blog\/wp-json\/wp\/v2\/tags?post=829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}